{"id":14852,"date":"2026-05-13T08:53:07","date_gmt":"2026-05-13T11:53:07","guid":{"rendered":"https:\/\/canela.rs.gov.br\/sitenovo\/?p=14852"},"modified":"2026-05-13T08:53:10","modified_gmt":"2026-05-13T11:53:10","slug":"canela-mantem-servicos-essenciais-e-atendimentos-durante-o-feriado-prolongado-veja-como-fica","status":"publish","type":"post","link":"https:\/\/canela.rs.gov.br\/sitenovo\/canela-mantem-servicos-essenciais-e-atendimentos-durante-o-feriado-prolongado-veja-como-fica\/","title":{"rendered":"Canela mant\u00e9m servi\u00e7os essenciais e atendimentos durante o feriado prolongado; veja como fica"},"content":{"rendered":"\n<p>A Prefeitura de Canela garante o funcionamento normalizado dos servi\u00e7os p\u00fablicos considerados essenciais durante o feriado prolongado da Ascens\u00e3o do Senhor. Nesta quinta e sexta-feira, dias 14 e 15 de maio, servi\u00e7os como o atendimento do Hospital de Caridade de Canela (para urg\u00eancias e emerg\u00eancias), da coleta seletiva de res\u00edduos, da fiscaliza\u00e7\u00e3o e o monitoramento de tr\u00e2nsito, al\u00e9m da manuten\u00e7\u00e3o dos parques p\u00fablicos e do Cemit\u00e9rio Municipal, seguem normalmente.<\/p>\n\n\n\n<p>O pr\u00e9dio administrativo da Prefeitura e as demais reparti\u00e7\u00f5es p\u00fablicas, incluindo as sedes das secretarias municipais, estar\u00e3o fechados de quinta-feira at\u00e9 domingo, dia 17. Os atendimentos retornam na segunda-feira, 18, em hor\u00e1rio habitual.<\/p>\n\n\n\n<p>No dia 15, sexta-feira, mant\u00e9m-se em funcionamento as Unidades B\u00e1sicas de Sa\u00fade (UBSs), a Farm\u00e1cia Municipal e o Centro de Aten\u00e7\u00e3o Psicossocial (Caps), garantindo atendimento \u00e0 popula\u00e7\u00e3o. No s\u00e1bado, 16 de maio, ocorre ainda a 6\u00aa edi\u00e7\u00e3o do Bota-Fora de res\u00edduos volumosos nos bairros Hort\u00eansias, Su\u00ed\u00e7a e Suzana, a cargo das Secretarias de Meio Ambiente e Urbanismo e de Obras, Servi\u00e7os Urbanos e Agricultura, a partir das 7h30.<\/p>\n\n\n\n<p><strong>Caravaggio<\/strong><\/p>\n\n\n\n<p>Nos dias 25 e 26 de maio, haver\u00e1 prolongamento do feriado pelo dia de Nossa Senhora de Caravaggio. Da mesma forma, est\u00e3o assegurados os servi\u00e7os p\u00fablicos essenciais, sendo mantido o atendimento em postos de sa\u00fade, Caps e Farm\u00e1cia Municipal na segunda-feira, dia 25.<\/p>\n\n\n\n<p><strong>Compensa\u00e7\u00e3o de expediente<\/strong><\/p>\n\n\n\n<p>Conforme previsto pelo Decreto n\u00ba Decreto n\u00ba 11.035, a suspens\u00e3o do expediente nos dias 15 e 25 de maio ser\u00e1 compensada pelos servidores p\u00fablicos em dois s\u00e1bados trabalhados &#8211; 30 de maio e 12 de setembro. O cumprimento ser\u00e1 em turno \u00fanico, das 7h \u00e0s 13h, com atendimento ao p\u00fablico das 8h \u00e0s 12h no Pa\u00e7o Municipal.<\/p>\n\n\n\n<p><em>Texto: Adriana Rabassa\/Prefeitura de Canela<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Prefeitura de Canela garante o funcionamento normalizado dos servi\u00e7os p\u00fablicos considerados essenciais durante o feriado prolongado da Ascens\u00e3o do Senhor. Nesta quinta e sexta-feira, dias 14 e 15 de maio, servi\u00e7os como o atendimento do Hospital de Caridade de Canela (para urg\u00eancias e emerg\u00eancias), da coleta seletiva de res\u00edduos, da fiscaliza\u00e7\u00e3o e o monitoramento [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":14853,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[39],"tags":[],"class_list":["post-14852","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-post_gestao-publica"],"_links":{"self":[{"href":"https:\/\/canela.rs.gov.br\/sitenovo\/wp-json\/wp\/v2\/posts\/14852","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canela.rs.gov.br\/sitenovo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/canela.rs.gov.br\/sitenovo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/canela.rs.gov.br\/sitenovo\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/canela.rs.gov.br\/sitenovo\/wp-json\/wp\/v2\/comments?post=14852"}],"version-history":[{"count":1,"href":"https:\/\/canela.rs.gov.br\/sitenovo\/wp-json\/wp\/v2\/posts\/14852\/revisions"}],"predecessor-version":[{"id":14854,"href":"https:\/\/canela.rs.gov.br\/sitenovo\/wp-json\/wp\/v2\/posts\/14852\/revisions\/14854"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canela.rs.gov.br\/sitenovo\/wp-json\/wp\/v2\/media\/14853"}],"wp:attachment":[{"href":"https:\/\/canela.rs.gov.br\/sitenovo\/wp-json\/wp\/v2\/media?parent=14852"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canela.rs.gov.br\/sitenovo\/wp-json\/wp\/v2\/categories?post=14852"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/canela.rs.gov.br\/sitenovo\/wp-json\/wp\/v2\/tags?post=14852"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}