{"id":22141,"date":"2019-10-14T17:23:19","date_gmt":"2019-10-14T20:23:19","guid":{"rendered":"https:\/\/canela.rs.gov.br\/siteantigo\/?p=22141"},"modified":"2020-10-29T07:49:10","modified_gmt":"2020-10-29T10:49:10","slug":"termo-no-11-2019-fomento","status":"publish","type":"publicacaolegal","link":"https:\/\/canela.rs.gov.br\/siteantigo\/publicacaolegal\/termo-no-11-2019-fomento\/","title":{"rendered":"Termo n\u00ba 11\/2019 &#8211; Fomento"},"content":{"rendered":"\n<div class=\"wp-block-file\"><a href=\"https:\/\/canela.rs.gov.br\/siteantigo\/wp-content\/uploads\/2019\/10\/Termo-n\u00ba-11-2019-Fomento-FCC-Festival-de-Bonecos-R-300.00000.pdf\">Termo n\u00ba 11\/2019 &#8211; Fomento &#8211; Funda\u00e7\u00e3o Cultural de Canela<\/a><a href=\"https:\/\/canela.rs.gov.br\/siteantigo\/wp-content\/uploads\/2019\/10\/Termo-n\u00ba-11-2019-Fomento-FCC-Festival-de-Bonecos-R-300.00000.pdf\" class=\"wp-block-file__button\" download>Baixar<\/a><\/div>\n","protected":false},"template":"","meta":{"_acf_changed":false,"_members_access_role":[],"_members_access_error":""},"tipo_pub_legal":[],"class_list":["post-22141","publicacaolegal","type-publicacaolegal","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/canela.rs.gov.br\/siteantigo\/wp-json\/wp\/v2\/publicacaolegal\/22141","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canela.rs.gov.br\/siteantigo\/wp-json\/wp\/v2\/publicacaolegal"}],"about":[{"href":"https:\/\/canela.rs.gov.br\/siteantigo\/wp-json\/wp\/v2\/types\/publicacaolegal"}],"wp:attachment":[{"href":"https:\/\/canela.rs.gov.br\/siteantigo\/wp-json\/wp\/v2\/media?parent=22141"}],"wp:term":[{"taxonomy":"tipo_pub_legal","embeddable":true,"href":"https:\/\/canela.rs.gov.br\/siteantigo\/wp-json\/wp\/v2\/tipo_pub_legal?post=22141"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}