{"id":20556,"date":"2019-07-30T13:58:23","date_gmt":"2019-07-30T16:58:23","guid":{"rendered":"https:\/\/canela.rs.gov.br\/siteantigo\/?p=20556"},"modified":"2020-10-29T07:49:11","modified_gmt":"2020-10-29T10:49:11","slug":"gabarito-preliminar-eleicao-conselho-tutelar","status":"publish","type":"publicacaolegal","link":"https:\/\/canela.rs.gov.br\/siteantigo\/publicacaolegal\/gabarito-preliminar-eleicao-conselho-tutelar\/","title":{"rendered":"GABARITO PRELIMINAR &#8211; Elei\u00e7\u00e3o Conselho Tutelar"},"content":{"rendered":"\n<div class=\"wp-block-file\"><a href=\"https:\/\/canela.rs.gov.br\/siteantigo\/wp-content\/uploads\/2019\/07\/G-CONSELHEIRO-TUTELAR.pdf\">Gabarito da Prova Escrita &#8211; Processo de Escolha dos Membros do Conselho Tutelar<\/a><a href=\"https:\/\/canela.rs.gov.br\/siteantigo\/wp-content\/uploads\/2019\/07\/G-CONSELHEIRO-TUTELAR.pdf\" class=\"wp-block-file__button\" download>Baixar<\/a><\/div>\n","protected":false},"template":"","meta":{"_acf_changed":false,"_members_access_role":[],"_members_access_error":""},"tipo_pub_legal":[],"class_list":["post-20556","publicacaolegal","type-publicacaolegal","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/canela.rs.gov.br\/siteantigo\/wp-json\/wp\/v2\/publicacaolegal\/20556","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canela.rs.gov.br\/siteantigo\/wp-json\/wp\/v2\/publicacaolegal"}],"about":[{"href":"https:\/\/canela.rs.gov.br\/siteantigo\/wp-json\/wp\/v2\/types\/publicacaolegal"}],"wp:attachment":[{"href":"https:\/\/canela.rs.gov.br\/siteantigo\/wp-json\/wp\/v2\/media?parent=20556"}],"wp:term":[{"taxonomy":"tipo_pub_legal","embeddable":true,"href":"https:\/\/canela.rs.gov.br\/siteantigo\/wp-json\/wp\/v2\/tipo_pub_legal?post=20556"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}