{"id":9268,"date":"2017-12-19T11:22:17","date_gmt":"2017-12-19T13:22:17","guid":{"rendered":"http:\/\/canela3.hospedagemdesites.ws\/?p=9268"},"modified":"2020-11-12T20:24:48","modified_gmt":"2020-11-12T23:24:48","slug":"secretaria-de-obras-realiza-servicos-nas-estradas-do-interior","status":"publish","type":"noticia","link":"https:\/\/canela.rs.gov.br\/siteantigo\/noticia\/secretaria-de-obras-realiza-servicos-nas-estradas-do-interior\/","title":{"rendered":"Secretaria de Obras realiza\u00a0 servi\u00e7os nas estradas do interior"},"content":{"rendered":"<p>A Prefeitura de Canela, por meio da Secretaria de Obras, Servi\u00e7os Urbanos e Agricultura, est\u00e1 com equipes mobilizadas e todo o maquin\u00e1rio pesado trabalhando em algumas localidades do interior do munic\u00edpio. Conforme o secret\u00e1rio titular da pasta, Luiz Cl\u00e1udio da Silva, os trabalhos nas estradas do interior iniciaram na semana passada e devem prosseguir nos pr\u00f3ximos dias.<br \/>\nJ\u00e1 foram executados servi\u00e7os de terraplana<span class=\"text_exposed_show\">gem em um avi\u00e1rio localizado na Linha Amoreiras, alargamento da estrada, patrolamento e implanta\u00e7\u00e3o de saibro na localidade Morro Alegre, al\u00e9m de patrolamentos no Morro Cal\u00e7ado, Canastra Alta e no trecho conhecido como Estrada Daniel (entre Amoreiras e Morro Cal\u00e7ado). \u201cEstamos nos dedicando ao interior com todas as m\u00e1quinas que temos dispon\u00edveis\u201d, afirma o secret\u00e1rio Luiz Cl\u00e1udio.<\/span><\/p>\n<div class=\"text_exposed_show\">\n<p>Fotos: Divulga\u00e7\u00e3o<\/p>\n<\/div>\n","protected":false},"author":2,"featured_media":9269,"parent":0,"template":"","meta":{"_acf_changed":false,"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[38,18,32],"assunto":[],"class_list":["post-9268","noticia","type-noticia","status-publish","has-post-thumbnail","hentry","category-gabinete","category-governanca","category-obras"],"acf":[],"_links":{"self":[{"href":"https:\/\/canela.rs.gov.br\/siteantigo\/wp-json\/wp\/v2\/noticia\/9268","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canela.rs.gov.br\/siteantigo\/wp-json\/wp\/v2\/noticia"}],"about":[{"href":"https:\/\/canela.rs.gov.br\/siteantigo\/wp-json\/wp\/v2\/types\/noticia"}],"author":[{"embeddable":true,"href":"https:\/\/canela.rs.gov.br\/siteantigo\/wp-json\/wp\/v2\/users\/2"}],"version-history":[{"count":1,"href":"https:\/\/canela.rs.gov.br\/siteantigo\/wp-json\/wp\/v2\/noticia\/9268\/revisions"}],"predecessor-version":[{"id":28310,"href":"https:\/\/canela.rs.gov.br\/siteantigo\/wp-json\/wp\/v2\/noticia\/9268\/revisions\/28310"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canela.rs.gov.br\/siteantigo\/wp-json\/wp\/v2\/media\/9269"}],"wp:attachment":[{"href":"https:\/\/canela.rs.gov.br\/siteantigo\/wp-json\/wp\/v2\/media?parent=9268"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canela.rs.gov.br\/siteantigo\/wp-json\/wp\/v2\/categories?post=9268"},{"taxonomy":"assunto","embeddable":true,"href":"https:\/\/canela.rs.gov.br\/siteantigo\/wp-json\/wp\/v2\/assunto?post=9268"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}