{"id":42616,"date":"2024-03-14T09:40:07","date_gmt":"2024-03-14T12:40:07","guid":{"rendered":"https:\/\/canela.rs.gov.br\/siteantigo\/?post_type=noticia&#038;p=42616"},"modified":"2024-03-14T09:40:07","modified_gmt":"2024-03-14T12:40:07","slug":"usuarios-do-caps-customizam-porta-retratos-para-a-brocker-turismo","status":"publish","type":"noticia","link":"https:\/\/canela.rs.gov.br\/siteantigo\/noticia\/usuarios-do-caps-customizam-porta-retratos-para-a-brocker-turismo\/","title":{"rendered":"Usu\u00e1rios do CAPs customizam porta-retratos para a Brocker Turismo"},"content":{"rendered":"<p>Usu\u00e1rios do Centro de Aten\u00e7\u00e3o Psicossocial (CAPs) de Canela t\u00eam encontrado na arte uma forma de express\u00e3o e inclus\u00e3o na sociedade. Recentemente, alguns usu\u00e1rios do CAPs tiveram a oportunidade de participar de um projeto especial em parceria com a Brocker Turismo, uma das principais empresas do ramo tur\u00edstico da regi\u00e3o.<\/p>\n<p>O projeto consistiu na customiza\u00e7\u00e3o de porta-retratos que foram entregues como recorda\u00e7\u00e3o aos premiados do 17\u00ba Trof\u00e9u Infinito, reconhecimento para os maiores players de turismo de lazer e eventos que geram grandes neg\u00f3cios para o destino Serra Ga\u00facha.<\/p>\n<p>Sob a orienta\u00e7\u00e3o de profissionais\u00a0<em>Kuka Patzinger, Rosane Moura e do estagi\u00e1rio Ary J\u00fanior\u00a0<\/em>os usu\u00e1rios puderam expressar sua criatividade e habilidades art\u00edsticas, decorando simples porta-retratos com flores customizadas e que refletem a singularidade e sensibilidade de seus criadores, proporcionando uma experi\u00eancia enriquecedora tanto para os participantes quanto para aqueles que ter\u00e3o a oportunidade de apreciar as obras.<\/p>\n<p>Para os usu\u00e1rios do CAPs, essa iniciativa representa mais do que simplesmente criar arte; \u00e9 uma forma de se sentirem valorizados e integrados \u00e0 sociedade, contribuindo de maneira significativa para o ambiente cultural e tur\u00edstico da cidade. Al\u00e9m disso, a parceria com a Brocker Turismo abre portas para novas oportunidades de colabora\u00e7\u00e3o e inclus\u00e3o social, demonstrando o potencial transformador da arte na vida das pessoas.<\/p>\n<p>A Brocker Turismo, por sua vez, enaltece a iniciativa como parte de seu compromisso com a responsabilidade social e o apoio \u00e0s comunidades locais. A empresa reconhece a import\u00e2ncia de promover a inclus\u00e3o e valoriza\u00e7\u00e3o de todos os indiv\u00edduos, e v\u00ea na arte uma poderosa ferramenta para alcan\u00e7ar esses objetivos.<\/p>\n<p>A colabora\u00e7\u00e3o entre o CAPs e a Brocker Turismo \u00e9 um exemplo inspirador de como a arte pode ser uma ponte para a inclus\u00e3o e o desenvolvimento comunit\u00e1rio. Essa parceria n\u00e3o apenas valoriza o talento e a criatividade dos usu\u00e1rios do CAPs, mas tamb\u00e9m fortalece os la\u00e7os entre a empresa e a comunidade, promovendo uma cultura de respeito, diversidade e solidariedade.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-42618\" src=\"https:\/\/canela.rs.gov.br\/siteantigo\/wp-content\/uploads\/2024\/03\/Caps1.jpg\" alt=\"\" width=\"1600\" height=\"1200\" srcset=\"https:\/\/canela.rs.gov.br\/siteantigo\/wp-content\/uploads\/2024\/03\/Caps1.jpg 1600w, https:\/\/canela.rs.gov.br\/siteantigo\/wp-content\/uploads\/2024\/03\/Caps1-300x225.jpg 300w, https:\/\/canela.rs.gov.br\/siteantigo\/wp-content\/uploads\/2024\/03\/Caps1-1024x768.jpg 1024w, https:\/\/canela.rs.gov.br\/siteantigo\/wp-content\/uploads\/2024\/03\/Caps1-768x576.jpg 768w, https:\/\/canela.rs.gov.br\/siteantigo\/wp-content\/uploads\/2024\/03\/Caps1-1536x1152.jpg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/><\/p>\n","protected":false},"author":2,"featured_media":42617,"parent":0,"template":"","meta":{"_acf_changed":false,"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[27],"assunto":[],"class_list":["post-42616","noticia","type-noticia","status-publish","has-post-thumbnail","hentry","category-assistencia"],"acf":[],"_links":{"self":[{"href":"https:\/\/canela.rs.gov.br\/siteantigo\/wp-json\/wp\/v2\/noticia\/42616","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canela.rs.gov.br\/siteantigo\/wp-json\/wp\/v2\/noticia"}],"about":[{"href":"https:\/\/canela.rs.gov.br\/siteantigo\/wp-json\/wp\/v2\/types\/noticia"}],"author":[{"embeddable":true,"href":"https:\/\/canela.rs.gov.br\/siteantigo\/wp-json\/wp\/v2\/users\/2"}],"version-history":[{"count":1,"href":"https:\/\/canela.rs.gov.br\/siteantigo\/wp-json\/wp\/v2\/noticia\/42616\/revisions"}],"predecessor-version":[{"id":42619,"href":"https:\/\/canela.rs.gov.br\/siteantigo\/wp-json\/wp\/v2\/noticia\/42616\/revisions\/42619"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canela.rs.gov.br\/siteantigo\/wp-json\/wp\/v2\/media\/42617"}],"wp:attachment":[{"href":"https:\/\/canela.rs.gov.br\/siteantigo\/wp-json\/wp\/v2\/media?parent=42616"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canela.rs.gov.br\/siteantigo\/wp-json\/wp\/v2\/categories?post=42616"},{"taxonomy":"assunto","embeddable":true,"href":"https:\/\/canela.rs.gov.br\/siteantigo\/wp-json\/wp\/v2\/assunto?post=42616"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}