{"id":41894,"date":"2023-12-19T09:18:43","date_gmt":"2023-12-19T12:18:43","guid":{"rendered":"https:\/\/canela.rs.gov.br\/siteantigo\/?post_type=noticia&#038;p=41894"},"modified":"2023-12-19T09:18:43","modified_gmt":"2023-12-19T12:18:43","slug":"passeio-ciclistico-foi-marcado-pela-solidariedade","status":"publish","type":"noticia","link":"https:\/\/canela.rs.gov.br\/siteantigo\/noticia\/passeio-ciclistico-foi-marcado-pela-solidariedade\/","title":{"rendered":"Passeio cicl\u00edstico foi marcado pela solidariedade"},"content":{"rendered":"<p>Andar de bicicleta \u00e9 um h\u00e1bito que faz parte da vida de muitas pessoas, seja como um meio de transporte, seja como um apoio das atividades f\u00edsicas ou dos momentos de lazer. Independentemente da finalidade, os benef\u00edcios do ciclismo s\u00e3o in\u00fameros tanto para o corpo quanto para a mente.<br \/>\nA Secretaria de Meio Ambiente e Urbanismo promoveu no s\u00e1bado \u00a0(16.12), um passeio cicl\u00edstico que saiu do pa\u00e7o municipal, percorreu as principais ruas de Canela e no Parque do Pal\u00e1cio houve uma pausa para orienta\u00e7\u00f5es e hidrata\u00e7\u00e3o, retornando pelo centro at\u00e9 o Parque do Lago, onde no local acontecia a feirinha com doa\u00e7\u00f5es de c\u00e3es do Cempra, filhotes da ONG Amor Sem Ra\u00e7a, distribui\u00e7\u00e3o de mudas de \u00e1rvores, ponto de coleta de eletr\u00f4nicos, comercializa\u00e7\u00e3o de produtos dos agricultores locais e cama el\u00e1stica para as crian\u00e7as que tamb\u00e9m se divertiram com a presen\u00e7a do Papai Noel.<br \/>\nDurante o evento foram distribu\u00eddos brindes e sorteadas duas bicicletas. Os participantes contribu\u00edram com um brinquedo que ser\u00e1 repassado \u00e0s crian\u00e7as atendidas pela Assist\u00eancia Social.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-41896\" src=\"https:\/\/canela.rs.gov.br\/siteantigo\/wp-content\/uploads\/2023\/12\/IMG_4502.jpeg\" alt=\"\" width=\"2048\" height=\"1536\" srcset=\"https:\/\/canela.rs.gov.br\/siteantigo\/wp-content\/uploads\/2023\/12\/IMG_4502.jpeg 2048w, https:\/\/canela.rs.gov.br\/siteantigo\/wp-content\/uploads\/2023\/12\/IMG_4502-300x225.jpeg 300w, https:\/\/canela.rs.gov.br\/siteantigo\/wp-content\/uploads\/2023\/12\/IMG_4502-1024x768.jpeg 1024w, https:\/\/canela.rs.gov.br\/siteantigo\/wp-content\/uploads\/2023\/12\/IMG_4502-768x576.jpeg 768w, https:\/\/canela.rs.gov.br\/siteantigo\/wp-content\/uploads\/2023\/12\/IMG_4502-1536x1152.jpeg 1536w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/> <img decoding=\"async\" class=\"alignnone size-full wp-image-41897\" src=\"https:\/\/canela.rs.gov.br\/siteantigo\/wp-content\/uploads\/2023\/12\/IMG_4515.jpeg\" alt=\"\" width=\"2048\" height=\"1536\" srcset=\"https:\/\/canela.rs.gov.br\/siteantigo\/wp-content\/uploads\/2023\/12\/IMG_4515.jpeg 2048w, https:\/\/canela.rs.gov.br\/siteantigo\/wp-content\/uploads\/2023\/12\/IMG_4515-300x225.jpeg 300w, https:\/\/canela.rs.gov.br\/siteantigo\/wp-content\/uploads\/2023\/12\/IMG_4515-1024x768.jpeg 1024w, https:\/\/canela.rs.gov.br\/siteantigo\/wp-content\/uploads\/2023\/12\/IMG_4515-768x576.jpeg 768w, https:\/\/canela.rs.gov.br\/siteantigo\/wp-content\/uploads\/2023\/12\/IMG_4515-1536x1152.jpeg 1536w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/> <img decoding=\"async\" class=\"alignnone size-full wp-image-41898\" src=\"https:\/\/canela.rs.gov.br\/siteantigo\/wp-content\/uploads\/2023\/12\/IMG_4509.jpeg\" alt=\"\" width=\"1536\" height=\"2048\" srcset=\"https:\/\/canela.rs.gov.br\/siteantigo\/wp-content\/uploads\/2023\/12\/IMG_4509.jpeg 1536w, https:\/\/canela.rs.gov.br\/siteantigo\/wp-content\/uploads\/2023\/12\/IMG_4509-225x300.jpeg 225w, https:\/\/canela.rs.gov.br\/siteantigo\/wp-content\/uploads\/2023\/12\/IMG_4509-768x1024.jpeg 768w, https:\/\/canela.rs.gov.br\/siteantigo\/wp-content\/uploads\/2023\/12\/IMG_4509-1152x1536.jpeg 1152w\" sizes=\"(max-width: 1536px) 100vw, 1536px\" \/><\/p>\n","protected":false},"author":2,"featured_media":41895,"parent":0,"template":"","meta":{"_acf_changed":false,"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[30],"assunto":[],"class_list":["post-41894","noticia","type-noticia","status-publish","has-post-thumbnail","hentry","category-meio-ambiente"],"acf":[],"_links":{"self":[{"href":"https:\/\/canela.rs.gov.br\/siteantigo\/wp-json\/wp\/v2\/noticia\/41894","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canela.rs.gov.br\/siteantigo\/wp-json\/wp\/v2\/noticia"}],"about":[{"href":"https:\/\/canela.rs.gov.br\/siteantigo\/wp-json\/wp\/v2\/types\/noticia"}],"author":[{"embeddable":true,"href":"https:\/\/canela.rs.gov.br\/siteantigo\/wp-json\/wp\/v2\/users\/2"}],"version-history":[{"count":1,"href":"https:\/\/canela.rs.gov.br\/siteantigo\/wp-json\/wp\/v2\/noticia\/41894\/revisions"}],"predecessor-version":[{"id":41899,"href":"https:\/\/canela.rs.gov.br\/siteantigo\/wp-json\/wp\/v2\/noticia\/41894\/revisions\/41899"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canela.rs.gov.br\/siteantigo\/wp-json\/wp\/v2\/media\/41895"}],"wp:attachment":[{"href":"https:\/\/canela.rs.gov.br\/siteantigo\/wp-json\/wp\/v2\/media?parent=41894"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canela.rs.gov.br\/siteantigo\/wp-json\/wp\/v2\/categories?post=41894"},{"taxonomy":"assunto","embeddable":true,"href":"https:\/\/canela.rs.gov.br\/siteantigo\/wp-json\/wp\/v2\/assunto?post=41894"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}