{"id":40910,"date":"2023-09-01T08:34:19","date_gmt":"2023-09-01T11:34:19","guid":{"rendered":"https:\/\/canela.rs.gov.br\/siteantigo\/?post_type=noticia&#038;p=40910"},"modified":"2023-09-01T08:34:19","modified_gmt":"2023-09-01T11:34:19","slug":"procon-de-canela-segue-com-a-acao-educativa-do-projeto-vitrine-legal-tem-preco","status":"publish","type":"noticia","link":"https:\/\/canela.rs.gov.br\/siteantigo\/noticia\/procon-de-canela-segue-com-a-acao-educativa-do-projeto-vitrine-legal-tem-preco\/","title":{"rendered":"Procon de Canela segue com a a\u00e7\u00e3o educativa do projeto Vitrine Legal tem Pre\u00e7o"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-40911\" src=\"https:\/\/canela.rs.gov.br\/siteantigo\/wp-content\/uploads\/2023\/09\/Operacao.jpeg\" alt=\"\" width=\"1080\" height=\"1080\" srcset=\"https:\/\/canela.rs.gov.br\/siteantigo\/wp-content\/uploads\/2023\/09\/Operacao.jpeg 1080w, https:\/\/canela.rs.gov.br\/siteantigo\/wp-content\/uploads\/2023\/09\/Operacao-300x300.jpeg 300w, https:\/\/canela.rs.gov.br\/siteantigo\/wp-content\/uploads\/2023\/09\/Operacao-1024x1024.jpeg 1024w, https:\/\/canela.rs.gov.br\/siteantigo\/wp-content\/uploads\/2023\/09\/Operacao-150x150.jpeg 150w, https:\/\/canela.rs.gov.br\/siteantigo\/wp-content\/uploads\/2023\/09\/Operacao-768x768.jpeg 768w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/p>\n<p>N\u00e3o \u00e9 dif\u00edcil encontrar estabelecimentos que exp\u00f5em seus produtos sem a devida etiquetagem de pre\u00e7os. Em raz\u00e3o da falta dessa informa\u00e7\u00e3o, muitas vezes o consumidor deixa de comprar o produto que deseja ou precisa solicit\u00e1-la ao vendedor. Mas voc\u00ea sabia que a exposi\u00e7\u00e3o do valor do produto \u00e9 uma obriga\u00e7\u00e3o dos estabelecimentos?<br \/>\nCom o objetivo de conscientizar e orientar os lojistas quanto a forma correta de exposi\u00e7\u00e3o da precifica\u00e7\u00e3o dos produtos, o Procon de Canela segue realizou com a a\u00e7\u00e3o educativa \u201cVitrine Legal tem Pre\u00e7o\u201d<br \/>\nA coordenadora do Procon, Deisi Stange, orienta que o pre\u00e7o de produtos e servi\u00e7os precisa estar vis\u00edvel e de forma permanente, enquanto o estabelecimento estiver aberto ao p\u00fablico.<br \/>\nA informa\u00e7\u00e3o deve constar o valor total \u00e0 vista, caso haja desconto ou parcelamento esta informa\u00e7\u00e3o nunca pode ser maior ou mais chamativa que o pre\u00e7o real do produto. Nos casos de financiamento ou parcelamento \u00e9 preciso mostrar o valor total a ser pago com financiamento, n\u00famero, tempo e valor das presta\u00e7\u00f5es, juros e encargos que fizerem parte do valor do parcelamento ou financiamento.<br \/>\nO C\u00f3digo de Defesa do Consumidor existe desde 1990 e traz como um de seus princ\u00edpios o acesso \u00e0 informa\u00e7\u00e3o ao consumidor. Exigir ou constranger o consumidor a fim de realizar a venda sem exibir e informar o consumidor sobre o verdadeiro pre\u00e7o a ser pago \u00e9 uma infra\u00e7\u00e3o ao direito do consumidor, pass\u00edvel de san\u00e7\u00e3o na medida do Decreto Municipal 9767\/2023.<br \/>\nAten\u00e7\u00e3o redobrada ainda para a exig\u00eancia de todo estabelecimento comercial possuir uma c\u00f3pia do C\u00f3digo de Defesa do Consumidor conforme a Lei Federal 12.291 de 2010. O Procon Municipal de Canela entende que n\u00e3o h\u00e1 necessidade de gastar dinheiro com a compra de um exemplar do CDC, bastando a impress\u00e3o atualizada e disponibilizada em local de f\u00e1cil acesso para atender o que determina a lei. Por exemplo o fornecedor pode entrar no site oficial do planalto e fazer a impress\u00e3o em papel sulfite, encadernar ou mesmo grampear e deixar em local vis\u00edvel para que os consumidores possam consultar. Os exemplares est\u00e3o dispon\u00edveis para aquisi\u00e7\u00e3o em livrarias online ou nos bazares da cidade.<br \/>\nO Procon de Canela segue a disposi\u00e7\u00e3o para d\u00favidas dos consumidores e para reclama\u00e7\u00f5es dos residentes em Canela via telefone (54)3282-5121 ou pelo WhatsApp (54)99138-1905.<\/p>\n","protected":false},"author":2,"featured_media":40911,"parent":0,"template":"","meta":{"_acf_changed":false,"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[212],"assunto":[],"class_list":["post-40910","noticia","type-noticia","status-publish","has-post-thumbnail","hentry","category-governo"],"acf":[],"_links":{"self":[{"href":"https:\/\/canela.rs.gov.br\/siteantigo\/wp-json\/wp\/v2\/noticia\/40910","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canela.rs.gov.br\/siteantigo\/wp-json\/wp\/v2\/noticia"}],"about":[{"href":"https:\/\/canela.rs.gov.br\/siteantigo\/wp-json\/wp\/v2\/types\/noticia"}],"author":[{"embeddable":true,"href":"https:\/\/canela.rs.gov.br\/siteantigo\/wp-json\/wp\/v2\/users\/2"}],"version-history":[{"count":1,"href":"https:\/\/canela.rs.gov.br\/siteantigo\/wp-json\/wp\/v2\/noticia\/40910\/revisions"}],"predecessor-version":[{"id":40912,"href":"https:\/\/canela.rs.gov.br\/siteantigo\/wp-json\/wp\/v2\/noticia\/40910\/revisions\/40912"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canela.rs.gov.br\/siteantigo\/wp-json\/wp\/v2\/media\/40911"}],"wp:attachment":[{"href":"https:\/\/canela.rs.gov.br\/siteantigo\/wp-json\/wp\/v2\/media?parent=40910"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canela.rs.gov.br\/siteantigo\/wp-json\/wp\/v2\/categories?post=40910"},{"taxonomy":"assunto","embeddable":true,"href":"https:\/\/canela.rs.gov.br\/siteantigo\/wp-json\/wp\/v2\/assunto?post=40910"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}