{"id":38221,"date":"2022-12-26T14:34:13","date_gmt":"2022-12-26T17:34:13","guid":{"rendered":"https:\/\/canela.rs.gov.br\/siteantigo\/?post_type=noticia&#038;p=38221"},"modified":"2022-12-26T14:34:13","modified_gmt":"2022-12-26T17:34:13","slug":"secretaria-de-saude-zera-a-fila-de-castracoes-agendadas-para-2022","status":"publish","type":"noticia","link":"https:\/\/canela.rs.gov.br\/siteantigo\/noticia\/secretaria-de-saude-zera-a-fila-de-castracoes-agendadas-para-2022\/","title":{"rendered":"Secretaria de Sa\u00fade zera a fila de castra\u00e7\u00f5es agendadas para 2022"},"content":{"rendered":"<p><span style=\"font-size: medium\">A Prefeitura de Canela segue disponibilizando recursos para investimentos na causa animal. Al\u00e9m da implementa\u00e7\u00e3o do Cempra \u2013 Centro Municipal de Prote\u00e7\u00e3o dos Animais de Canela, inaugurado em mar\u00e7o deste ano, a Secretaria de Sa\u00fade tamb\u00e9m promoveu um mutir\u00e3o nos \u00faltimos meses em parceria com cl\u00ednicas veterin\u00e1rias do munic\u00edpio, com o objetivo de zerar a fila de espera para castra\u00e7\u00f5es de c\u00e3es e gatos. Ao todo foram investidos R$ 253.332,48 ao longo de 2022, possibilitando a realiza\u00e7\u00e3o de 1.528 cirurgias de castra\u00e7\u00e3o. <\/span><\/p>\n<p><span style=\"font-size: medium\">O secret\u00e1rio de Sa\u00fade, Leandro Gralha, lembra que em mar\u00e7o deste ano eram 1.214 animais aguardando na fila de espera e que este n\u00famero s\u00f3 foi zerado devido ao apoio do prefeito Constantino Orsolin que compreendeu a necessidade de destinar mais recursos para esta \u00e1rea. \u201cO controle do n\u00famero de animais no munic\u00edpio \u00e9 uma prioridade para a Secretaria de Sa\u00fade e tamb\u00e9m ser\u00e1 uma bandeira deste governo! Isso s\u00f3 est\u00e1 sendo poss\u00edvel devido a dedica\u00e7\u00e3o dos nossos servidores e o empenho dos veterin\u00e1rios parceiros\u201d, comentou Leandro Gralha, fazendo um agradecimento especial ao vereador Jer\u00f4nimo Terra Rolim (PDT) pela destina\u00e7\u00e3o de R$ 50 mil atrav\u00e9s de emenda parlamentar, para auxiliar nas castra\u00e7\u00f5es. \u201cUtilizamos este valor para castrar todos animais que est\u00e3o abrigados no Cempra\u201d, revela Gralha. <\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-size: medium\"><b>PROGRAMA SER\u00c1 RETOMADO EM JANEIRO<\/b><\/span><\/p>\n<p><span style=\"font-size: medium\">O programa de castra\u00e7\u00f5es ter\u00e1 continuidade em 2023 e para o pr\u00f3ximo m\u00eas de janeiro j\u00e1 est\u00e3o agendadas mais 99 cirurgias. O secret\u00e1rio Leandro Gralha faz um apelo aos propriet\u00e1rios dos animais, para que compare\u00e7am nas datas agendadas para as cirurgias. \u201cSomente neste ano foram registrados 964 cancelamentos! Isso representa um atraso enorme para o programa e a sa\u00fade p\u00fablica em nosso munic\u00edpio, pois acaba prejudicando fam\u00edlias que est\u00e3o aguardando ansiosamente na fila para terem seus animais de estima\u00e7\u00e3o castrados\u201d, avalia Gralha. <\/span><\/p>\n<p><span style=\"font-size: medium\">Mais informa\u00e7\u00f5es sobre o programa de castra\u00e7\u00f5es diretamente com o Departamento de Vigil\u00e2ncia Sanit\u00e1ria, pelo telefone (54) 3282-5170. <\/span><\/p>\n","protected":false},"author":2,"featured_media":38222,"parent":0,"template":"","meta":{"_acf_changed":false,"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[26],"assunto":[],"class_list":["post-38221","noticia","type-noticia","status-publish","has-post-thumbnail","hentry","category-saude"],"acf":[],"_links":{"self":[{"href":"https:\/\/canela.rs.gov.br\/siteantigo\/wp-json\/wp\/v2\/noticia\/38221","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canela.rs.gov.br\/siteantigo\/wp-json\/wp\/v2\/noticia"}],"about":[{"href":"https:\/\/canela.rs.gov.br\/siteantigo\/wp-json\/wp\/v2\/types\/noticia"}],"author":[{"embeddable":true,"href":"https:\/\/canela.rs.gov.br\/siteantigo\/wp-json\/wp\/v2\/users\/2"}],"version-history":[{"count":1,"href":"https:\/\/canela.rs.gov.br\/siteantigo\/wp-json\/wp\/v2\/noticia\/38221\/revisions"}],"predecessor-version":[{"id":38223,"href":"https:\/\/canela.rs.gov.br\/siteantigo\/wp-json\/wp\/v2\/noticia\/38221\/revisions\/38223"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canela.rs.gov.br\/siteantigo\/wp-json\/wp\/v2\/media\/38222"}],"wp:attachment":[{"href":"https:\/\/canela.rs.gov.br\/siteantigo\/wp-json\/wp\/v2\/media?parent=38221"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canela.rs.gov.br\/siteantigo\/wp-json\/wp\/v2\/categories?post=38221"},{"taxonomy":"assunto","embeddable":true,"href":"https:\/\/canela.rs.gov.br\/siteantigo\/wp-json\/wp\/v2\/assunto?post=38221"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}