{"id":36789,"date":"2022-07-13T13:21:59","date_gmt":"2022-07-13T16:21:59","guid":{"rendered":"https:\/\/canela.rs.gov.br\/siteantigo\/?post_type=noticia&#038;p=36789"},"modified":"2022-07-13T13:24:35","modified_gmt":"2022-07-13T16:24:35","slug":"festa-colonial-inicia-nesta-sexta-feira-na-peaca-joao-correa","status":"publish","type":"noticia","link":"https:\/\/canela.rs.gov.br\/siteantigo\/noticia\/festa-colonial-inicia-nesta-sexta-feira-na-peaca-joao-correa\/","title":{"rendered":"Festa Colonial inicia nesta sexta-feira na Pra\u00e7a Jo\u00e3o Corr\u00eaa"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p>A Pra\u00e7a Jo\u00e3o Corr\u00eaa recebe a partir de amanh\u00e3 (15), a 28\u00b0 Festa Colonial. Uma realiza\u00e7\u00e3o da Prefeitura Municipal por meio da Secretaria de Turismo e Cultura e a Secretaria de Obras, com a Emater e o Sindicato dos Trabalhadores Rurais, com apoio da Sicredi Pioneira e da Cervejaria Farol.<\/p>\n<p>O evento inicia \u00e0s 18h com a apresenta\u00e7\u00e3o do Grupo de dan\u00e7as do Garfo e Bombacha. J\u00e1 a cerim\u00f4nia oficial de abertura ocorre no s\u00e1bado (16), \u00e0s 11h.<\/p>\n<p>Neste ano a Festa Colonial conta com 14 fam\u00edlias de agricultores do interior do munic\u00edpio, respons\u00e1veis pela gastronomia. S\u00e3o in\u00fameras op\u00e7\u00f5es de comidas t\u00edpicas deste per\u00edodo, a pre\u00e7os acess\u00edveis e sabor sem igual.<\/p>\n<p>Vale lembrar que as inscri\u00e7\u00f5es para o Passeio Cicl\u00edstico, o Festican- Festival da can\u00e7\u00e3o e a corte de 2023 ainda est\u00e3o abertas. Mais informa\u00e7\u00f5es atrav\u00e9s do site: canela.com.br<\/p>\n<p><b>Programa\u00e7\u00e3o<\/b><\/p>\n<p><b>Sexta \u2013 15\/7<\/b><\/p>\n<p>18h &#8211; Grupo de Dan\u00e7as Garfo e Bombacha<\/p>\n<p>19h &#8211; Felipe Moschen e De-l\u00ea Surungo<\/p>\n<p>&nbsp;<\/p>\n<p><strong>S\u00e1bado &#8211; 16\/7<\/strong><\/p>\n<p>11h &#8211; Abertura oficial<\/p>\n<p>12h &#8211; Tiago e Daniel<\/p>\n<p>15h &#8211; Cortejo soberanas, bandinha e colonos, saindo da Catedral de Pedra.<\/p>\n<p>15h30 \u2013 Jonas Santos e Banda<\/p>\n<p>17h &#8211; Kedson e Arlan<\/p>\n<p>20h &#8211; Amaranto e seu Conjunto<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Domingo \u2013 17\/7<\/strong><\/p>\n<p>12h &#8211; Kerolin Acordeonista &amp; seu pai<\/p>\n<p>16h &#8211; Amantino e Grupo Badala\u00e7\u00e3o<\/p>\n<p>18h15 &#8211; Grupo de Dan\u00e7as folcl\u00f3ricas Miesbach<\/p>\n<p>20h &#8211; Edson Borba e Quarteto Serrano<\/p>\n<p><b>Segunda-feira \u2013 18\/7<\/b><\/p>\n<p>12h &#8211; Fernando Lima<\/p>\n<p>17h &#8211; Marco e Ol\u00e1vio<\/p>\n<p>20h &#8211; Os Tauras da Serra<\/p>\n<p><b>Ter\u00e7a-feira &#8211; 19\/7 <\/b><\/p>\n<p>12h &#8211; Edy Aguiar<\/p>\n<p>15h &#8211; Tiago Wagner e Banda<\/p>\n<p>18h &#8211; Coral Trentino<\/p>\n<p>20h &#8211; Pampa e Vanera<\/p>\n<p><b>Quarta-feira &#8211; 20\/07 <\/b><\/p>\n<p>12h &#8211; Felipe Moschen &amp; De-l\u00ea Surungo<\/p>\n<p>15h &#8211; Grupo Marca do Tempo<\/p>\n<p>17h30 &#8211; Grupo Tutti Italiani<\/p>\n<p>18h30 \u2013 Festican<\/p>\n<p><b>Quinta-feira \u2013 21\/7<\/b><\/p>\n<p>12h &#8211; Fabinho Pereira<\/p>\n<p>15h &#8211; Grupo de Dan\u00e7as Aldeia Ind\u00edgena Kaingang<\/p>\n<p>16h &#8211; Oficina de Gastr\u00f4nonia<\/p>\n<p>17h &#8211; Lauri Duarte e Banda<\/p>\n<p>18h30 &#8211; Festican (ACR33)<\/p>\n<p><b>Sexta-feira \u2013 22\/7<\/b><\/p>\n<p>12h &#8211; Fernando Lima<\/p>\n<p>15h &#8211; Conta\u00e7\u00e3o de Hist\u00f3rias<\/p>\n<p>17h \u2013 Retruco<\/p>\n<p>18h30 &#8211; Festican (ACR3)<\/p>\n<p>S\u00e1bado \u2013 23\/7<\/p>\n<p>12h &#8211; Edy Aguiar<\/p>\n<p>15h \u2013 Cortejo<\/p>\n<p>15h30 &#8211; Musical Horizonte<\/p>\n<p>18h &#8211; Grupo de Dan\u00e7as Folcl\u00f3ricas Miesbach<\/p>\n<p>20h &#8211; Jonas Santos e Banda<\/p>\n<p>Domingo \u2013 24\/7<\/p>\n<p>12h &#8211; Coral Nossa Senhora da Pompeia<\/p>\n<p>16h &#8211; Cassio Amaral e Grupo Tropeiros da Tradi\u00e7\u00e3o<\/p>\n<p>18h15 &#8211; Conjunto Folcl\u00f3rico Os Tapejaras<\/p>\n<p>20h &#8211; Marca do Tempo<\/p>\n<p><b>Segunda &#8211; 25\/07 <\/b><\/p>\n<p>14h &#8211; Grupo Amigos da Alegria<\/p>\n<p>17h &#8211; Pampa e Vanera<\/p>\n<p>20h &#8211; C\u00e1ssio Amaral e Grupo Tropeiros da Tradi\u00e7\u00e3o<\/p>\n<p><b>Ter\u00e7a-feira \u2013 26\/7<\/b><\/p>\n<p>12h &#8211; Sombra Del Ayer<\/p>\n<p>15h &#8211; Marcos e Ol\u00e1vio<\/p>\n<p>18h &#8211; Coral Trentino<\/p>\n<p>20h &#8211; Lauri Duarte e Banda<\/p>\n<p><b>Quarta-feira \u2013 27\/7<\/b><\/p>\n<p>12h &#8211; Juliano Bolfe<\/p>\n<p>15h &#8211; Amantino e Grupo Badala\u00e7\u00e3o<\/p>\n<p>18h &#8211; Jonas e Daniel<\/p>\n<p>20h &#8211; Fabinho Pereira e Banda<\/p>\n<p><b>Quinta-feira \u2013 28\/7<\/b><\/p>\n<p>12h &#8211; Sombra Del Ayer<\/p>\n<p>15h &#8211; Grupo de Dan\u00e7a Aldeia Ind\u00edgena Kaingang<\/p>\n<p>16h &#8211; Oficina de Gastronomia<\/p>\n<p>18h &#8211; Os Tauras da Serra<\/p>\n<p>20h &#8211; Retruco<\/p>\n<p><b>Sexta-feira &#8211; 29\/7 <\/b><\/p>\n<p>12h &#8211; Grupo Tutti Italiani<\/p>\n<p>15h &#8211; Conta\u00e7\u00e3o de Hist\u00f3ria<\/p>\n<p>16h &#8211; Grupo Amigos da Alegria<\/p>\n<p>18h &#8211; Juliano Bolfe<\/p>\n<p>20h &#8211; Edson Borba e Quarteto Serrano<\/p>\n<p><b>S\u00e1bado \u2013 31\/7<\/b><\/p>\n<p>12h &#8211; Tiago e Daniel<\/p>\n<p>15h \u2013 Cortejo<\/p>\n<p>15h30 &#8211; Banda alem\u00e3 itinerante<\/p>\n<p>17h &#8211; Escolha das Soberanas<\/p>\n<p>18h &#8211; Banda Teste<\/p>\n<p>20h &#8211; Tiago Wagner e Banda<\/p>\n<p><b>Domingo \u2013 31\/7<\/b><\/p>\n<p>12h &#8211; Kedson e Arlan<\/p>\n<p>16h &#8211; Musical Horizonte<\/p>\n<p>18h15 &#8211; Conjunto Folcl\u00f3rico Os Tapejaras<\/p>\n<p>20h &#8211; Amaranto e seu Conjunto<\/p>\n","protected":false},"author":2,"featured_media":36790,"parent":0,"template":"","meta":{"_acf_changed":false,"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[],"assunto":[],"class_list":["post-36789","noticia","type-noticia","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/canela.rs.gov.br\/siteantigo\/wp-json\/wp\/v2\/noticia\/36789","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canela.rs.gov.br\/siteantigo\/wp-json\/wp\/v2\/noticia"}],"about":[{"href":"https:\/\/canela.rs.gov.br\/siteantigo\/wp-json\/wp\/v2\/types\/noticia"}],"author":[{"embeddable":true,"href":"https:\/\/canela.rs.gov.br\/siteantigo\/wp-json\/wp\/v2\/users\/2"}],"version-history":[{"count":3,"href":"https:\/\/canela.rs.gov.br\/siteantigo\/wp-json\/wp\/v2\/noticia\/36789\/revisions"}],"predecessor-version":[{"id":36793,"href":"https:\/\/canela.rs.gov.br\/siteantigo\/wp-json\/wp\/v2\/noticia\/36789\/revisions\/36793"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canela.rs.gov.br\/siteantigo\/wp-json\/wp\/v2\/media\/36790"}],"wp:attachment":[{"href":"https:\/\/canela.rs.gov.br\/siteantigo\/wp-json\/wp\/v2\/media?parent=36789"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canela.rs.gov.br\/siteantigo\/wp-json\/wp\/v2\/categories?post=36789"},{"taxonomy":"assunto","embeddable":true,"href":"https:\/\/canela.rs.gov.br\/siteantigo\/wp-json\/wp\/v2\/assunto?post=36789"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}