{"id":23984,"date":"2020-01-16T11:15:23","date_gmt":"2020-01-16T14:15:23","guid":{"rendered":"https:\/\/canela.rs.gov.br\/siteantigo\/?p=23984"},"modified":"2020-11-12T20:22:09","modified_gmt":"2020-11-12T23:22:09","slug":"academia-municipal-em-nova-sede-a-partir-de-segunda-feira","status":"publish","type":"noticia","link":"https:\/\/canela.rs.gov.br\/siteantigo\/noticia\/academia-municipal-em-nova-sede-a-partir-de-segunda-feira\/","title":{"rendered":"Academia Municipal em nova sede a partir da pr\u00f3xima quarta-feira"},"content":{"rendered":"\n<p>A Academia Municipal de Canela passa a atender em nova sede a partir de quarta-feira (22): na rua Leopoldo Prux, n\u00ba 14, esquina com a Rua Dona Carlinda. O local, na entrada do bairro Santa Terezinha, antes abrigava a Secretaria Municipal de Sa\u00fade.<\/p>\n\n\n\n<p>Para\no oferecimento dos servi\u00e7os ser\u00e1 utilizado apenas\no\nprimeiro piso, a fim de favorecer acessibilidade aos usu\u00e1rios. \u201c\u00c9\num ponto positivo, pois no local anterior, no pr\u00e9dio da\nReceita Federal, a Academia ficava no segundo piso\u201d, diz o\nsecret\u00e1rio de Sa\u00fade Vilmar Santos.<\/p>\n\n\n\n<p>Nesta\nsemana, foi iniciada a transfer\u00eancia de equipamentos como as\nesteiras, faltando poucos ajustes para o in\u00edcio dos trabalhos.\nSegundo a educadora f\u00edsica Patr\u00edcia Liesenfeld, coordenadora, o\nlocal abrigar\u00e1 uma sala para aulas de medita\u00e7\u00e3o, de ioga e de\nritmos, al\u00e9m de um almoxarifado. \n<\/p>\n\n\n\n<p>Em\noutra sala, ser\u00e3o aplicadas as pr\u00e1ticas integrativas \u2013\nfitoterapia, auriculoterapia e, logo mais, acupuntura. \u201c\u00c9 um\nespa\u00e7o mais arejado, com rampa de acesso, bem pr\u00f3prio para uma\nacademia\u201d, elogia Patr\u00edcia.<\/p>\n\n\n\n<p>A\nAcademia Municipal funciona de segunda a sexta-feira, das 7h ao\nmeio-dia e das 13h \u00e0s 19h. A participa\u00e7\u00e3o \u00e9 gratuita e aberta \u00e0\ncomunidade, mas \u00e9 preciso passar por encaminhamento m\u00e9dico em\nalguma unidade b\u00e1sica de sa\u00fade. \n<\/p>\n","protected":false},"author":2,"featured_media":23985,"parent":0,"template":"","meta":{"_acf_changed":false,"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[26],"assunto":[],"class_list":["post-23984","noticia","type-noticia","status-publish","has-post-thumbnail","hentry","category-saude"],"acf":[],"_links":{"self":[{"href":"https:\/\/canela.rs.gov.br\/siteantigo\/wp-json\/wp\/v2\/noticia\/23984","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canela.rs.gov.br\/siteantigo\/wp-json\/wp\/v2\/noticia"}],"about":[{"href":"https:\/\/canela.rs.gov.br\/siteantigo\/wp-json\/wp\/v2\/types\/noticia"}],"author":[{"embeddable":true,"href":"https:\/\/canela.rs.gov.br\/siteantigo\/wp-json\/wp\/v2\/users\/2"}],"version-history":[{"count":1,"href":"https:\/\/canela.rs.gov.br\/siteantigo\/wp-json\/wp\/v2\/noticia\/23984\/revisions"}],"predecessor-version":[{"id":27384,"href":"https:\/\/canela.rs.gov.br\/siteantigo\/wp-json\/wp\/v2\/noticia\/23984\/revisions\/27384"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canela.rs.gov.br\/siteantigo\/wp-json\/wp\/v2\/media\/23985"}],"wp:attachment":[{"href":"https:\/\/canela.rs.gov.br\/siteantigo\/wp-json\/wp\/v2\/media?parent=23984"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canela.rs.gov.br\/siteantigo\/wp-json\/wp\/v2\/categories?post=23984"},{"taxonomy":"assunto","embeddable":true,"href":"https:\/\/canela.rs.gov.br\/siteantigo\/wp-json\/wp\/v2\/assunto?post=23984"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}